{"id":212,"count":5,"description":"","link":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/","name":"NOVEDADES MATE Sx TU","slug":"novedades-mate-sx-tu","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/\" \/>\n<meta property=\"og:site_name\" content=\"MATESxTU educaci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@elenabarberomxt\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/\",\"url\":\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/\",\"name\":\"Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/www.matesxtu.es\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.matesxtu.es\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NOVEDADES MATE Sx TU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.matesxtu.es\/es\/#website\",\"url\":\"https:\/\/www.matesxtu.es\/es\/\",\"name\":\"MATESxTU educaci\u00f3n\",\"description\":\"MATESxTU  = + x TODOS\",\"publisher\":{\"@id\":\"https:\/\/www.matesxtu.es\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.matesxtu.es\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.matesxtu.es\/es\/#organization\",\"name\":\"MATESxTU Academia de matematicas\",\"url\":\"https:\/\/www.matesxtu.es\/es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.matesxtu.es\/es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.matesxtu.es\/es\/wp-content\/uploads\/sites\/2\/2021\/02\/logo_matesxtu_A4-2-e1612497302468.png\",\"contentUrl\":\"https:\/\/www.matesxtu.es\/es\/wp-content\/uploads\/sites\/2\/2021\/02\/logo_matesxtu_A4-2-e1612497302468.png\",\"width\":588,\"height\":499,\"caption\":\"MATESxTU Academia de matematicas\"},\"image\":{\"@id\":\"https:\/\/www.matesxtu.es\/es\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Matesxtu-1465218103742467\/\",\"https:\/\/x.com\/elenabarberomxt\",\"https:\/\/www.instagram.com\/matesxtu\/\",\"https:\/\/www.linkedin.com\/in\/elena-barbero-revert\u00e9-aa8a4160\/\",\"https:\/\/www.youtube.com\/channel\/UCYS6kEJxsS2mT6VGEkNFOFQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/","og_locale":"es_ES","og_type":"article","og_title":"Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n","og_url":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/","og_site_name":"MATESxTU educaci\u00f3n","twitter_card":"summary_large_image","twitter_site":"@elenabarberomxt","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/","url":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/","name":"Arxius de NOVEDADES MATE Sx TU - MATESxTU educaci\u00f3n","isPartOf":{"@id":"https:\/\/www.matesxtu.es\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.matesxtu.es\/es\/tag\/novedades-mate-sx-tu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.matesxtu.es\/es\/"},{"@type":"ListItem","position":2,"name":"NOVEDADES MATE Sx TU"}]},{"@type":"WebSite","@id":"https:\/\/www.matesxtu.es\/es\/#website","url":"https:\/\/www.matesxtu.es\/es\/","name":"MATESxTU educaci\u00f3n","description":"MATESxTU  = + x TODOS","publisher":{"@id":"https:\/\/www.matesxtu.es\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.matesxtu.es\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.matesxtu.es\/es\/#organization","name":"MATESxTU Academia de matematicas","url":"https:\/\/www.matesxtu.es\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.matesxtu.es\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.matesxtu.es\/es\/wp-content\/uploads\/sites\/2\/2021\/02\/logo_matesxtu_A4-2-e1612497302468.png","contentUrl":"https:\/\/www.matesxtu.es\/es\/wp-content\/uploads\/sites\/2\/2021\/02\/logo_matesxtu_A4-2-e1612497302468.png","width":588,"height":499,"caption":"MATESxTU Academia de matematicas"},"image":{"@id":"https:\/\/www.matesxtu.es\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Matesxtu-1465218103742467\/","https:\/\/x.com\/elenabarberomxt","https:\/\/www.instagram.com\/matesxtu\/","https:\/\/www.linkedin.com\/in\/elena-barbero-revert\u00e9-aa8a4160\/","https:\/\/www.youtube.com\/channel\/UCYS6kEJxsS2mT6VGEkNFOFQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.matesxtu.es\/es\/wp-json\/wp\/v2\/tags\/212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.matesxtu.es\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.matesxtu.es\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.matesxtu.es\/es\/wp-json\/wp\/v2\/posts?tags=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}